{"id":1038,"date":"2025-09-16T19:43:10","date_gmt":"2025-09-16T19:43:10","guid":{"rendered":"https:\/\/ninja-icecream.com\/?p=1038"},"modified":"2026-02-11T14:58:43","modified_gmt":"2026-02-11T14:58:43","slug":"sorvete-de-maca-assada-e-xarope-de-bordo","status":"publish","type":"post","link":"https:\/\/ninja-icecream.com\/pt\/sorvete-de-maca-assada-e-xarope-de-bordo\/","title":{"rendered":"Sorvete de ma\u00e7\u00e3 assada e xarope de bordo para Ninja Creami &amp; Swirl"},"content":{"rendered":"\n<p>Tu veux une glace qui sent bon l\u2019automne et les desserts faits maison ? Cette recette va te faire fondre. Imagine des pommes doucement r\u00f4ties, encore ti\u00e8des, caram\u00e9lis\u00e9es juste comme il faut, puis m\u00e9lang\u00e9es \u00e0 la douceur sucr\u00e9e du sirop d\u2019\u00e9rable. Avec ton Ninja, \u00e7a se transforme en une glace onctueuse, pleine de r\u00e9confort.<\/p>\n\n\n\n<p>Chaque cuill\u00e8re, c\u2019est un m\u00e9lange de saveurs douces et chaleureuses : le fruit fondant, le petit go\u00fbt caram\u00e9lis\u00e9, et ce parfum d\u2019\u00e9rable qui rappelle les balades au Canada. Une vraie glace cocooning, parfaite pour se r\u00e9galer \u00e0 la maison.<\/p>\n\n\n<div class=\"wp-block-wpzoom-recipe-card-block-recipe-card is-style-default header-content-align-center block-alignment-left\" id=\"wpzoom-recipe-card\"><div class=\"recipe-card-image\">\n\t\t\t\t<figure>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-16-sept.-2025-a-21_42_36-800x530.png\" class=\"wpzoom-recipe-card-image\" alt=\"Glace aux pommes r\u00f4ties et au sirop d&#039;\u00e9rable\" id=\"1039\" \/>\n\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t<div class=\"wpzoom-recipe-card-print-link\">\n\t            <a class=\"btn-print-link no-print\" href=\"#wpzoom-recipe-card\" title=\"Print directions...\" style=\"background-color: #222222;\" data-servings-size=\"4\" data-recipe-id=\"1038\">\n\t            \t<SVG class=\"wpzoom-rcb-icon-print-link\" viewBox=\"0 0 32 32\" width=\"32\" height=\"32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n \t            \t    <g data-name=\"Layer 55\" id=\"Layer_55\">\n \t            \t        <Path class=\"wpzoom-rcb-print-icon\" d=\"M28,25H25a1,1,0,0,1,0-2h3a1,1,0,0,0,1-1V10a1,1,0,0,0-1-1H4a1,1,0,0,0-1,1V22a1,1,0,0,0,1,1H7a1,1,0,0,1,0,2H4a3,3,0,0,1-3-3V10A3,3,0,0,1,4,7H28a3,3,0,0,1,3,3V22A3,3,0,0,1,28,25Z\" \/>\n \t            \t        <Path class=\"wpzoom-rcb-print-icon\" d=\"M25,31H7a1,1,0,0,1-1-1V20a1,1,0,0,1,1-1H25a1,1,0,0,1,1,1V30A1,1,0,0,1,25,31ZM8,29H24V21H8Z\" \/>\n \t            \t        <Path class=\"wpzoom-rcb-print-icon\" d=\"M25,9a1,1,0,0,1-1-1V3H8V8A1,1,0,0,1,6,8V2A1,1,0,0,1,7,1H25a1,1,0,0,1,1,1V8A1,1,0,0,1,25,9Z\" \/>\n \t            \t        <rect class=\"wpzoom-rcb-print-icon\" height=\"2\" width=\"2\" x=\"24\" y=\"11\" \/>\n \t            \t        <rect class=\"wpzoom-rcb-print-icon\" height=\"2\" width=\"4\" x=\"18\" y=\"11\" \/>\n \t            \t    <\/g>\n \t            \t<\/SVG>\n\t                <span>Print<\/span>\n\t            <\/a>\n\t        <\/div>\n\t\t            <\/figcaption>\n\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t\t<div class=\"recipe-card-heading\">\n\t\t\t\t<h2 class=\"recipe-card-title\">Glace aux pommes r\u00f4ties et au sirop d&rsquo;\u00e9rable<\/h2><span class=\"recipe-card-course\">Course: <mark>Glaces<\/mark><\/span><span class=\"recipe-card-difficulty\">Difficulty: <mark>Moyenne<\/mark><\/span><\/div><div class=\"recipe-card-details\"><div class=\"details-items\"><div class=\"detail-item detail-item-0\"><span class=\"detail-item-icon oldicon oldicon-food\" style=\"color: #6d767f;\"><\/span><span class=\"detail-item-label\">Portions<\/span><p class=\"detail-item-value\">4<\/p><span class=\"detail-item-unit\">portions<\/span><\/div><\/div><\/div><div class=\"recipe-card-ingredients\"><h3 class=\"ingredients-title\">Ingredients<\/h3><ul class=\"ingredients-list layout-1-column\"><li id=\"wpzoom-rcb-ingredient-item-68c9bb68650f1\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\">3 <strong>pommes<\/strong><\/span><\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-68c9bb68650f2\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\">2 pots de <strong>yaourt grec<\/strong><\/span><\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-68c9bb68650f3\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\">1 morceau de <strong>beurre<\/strong><\/span><\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-68c9bb68650f4\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\">3 cuill\u00e8res \u00e0 soupe de <strong>sirop d\u2019\u00e9rable<\/strong><\/span><\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-175805127053687\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\">Environ 3 cuill\u00e8res \u00e0 soupe de <strong>cassonade<\/strong><\/span><\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-175805127150492\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\"><strong>Cannelle<\/strong><\/span><\/p><\/li><li id=\"wpzoom-rcb-ingredient-item-1758051362852209\" class=\"ingredient-item\"><span class=\"tick-circle\"><\/span><p class=\"ingredient-item-name is-strikethrough-active\"><span class=\"wpzoom-rcb-ingredient-name\">10 \u00e0 20 g de <strong>lait concentr\u00e9 sucr\u00e9<\/strong><\/span><\/p><\/li><\/ul><\/div><div class=\"recipe-card-directions\"><h3 class=\"directions-title\">Directions<\/h3><ul class=\"directions-list\"><li id=\"wpzoom-rcb-direction-step-68c9bb68650f6\" class=\"direction-step\"><strong>Pr\u00e9pare les pommes r\u00f4ties<\/strong><br \/>\u00c9pluche les pommes, retire le c\u0153ur puis coupe-les en petits morceaux. Mets-les dans une casserole avec le beurre, le sirop d\u2019\u00e9rable, la cassonade et une bonne dose de cannelle. Fais cuire \u00e0 feu moyen jusqu\u2019\u00e0 ce que les pommes soient bien tendres, caram\u00e9lis\u00e9es et dor\u00e9es. Si n\u00e9cessaire, ajoute un petit filet d\u2019eau pour \u00e9viter que \u00e7a accroche.<\/li><li id=\"wpzoom-rcb-direction-step-68c9bb68650f7\" class=\"direction-step\"><strong>Laisse refroidir<\/strong><br \/>Quand les pommes ont une belle couleur caramel et une texture fondante, retire la casserole du feu et laisse compl\u00e8tement refroidir.<\/li><li id=\"wpzoom-rcb-direction-step-68c9bb68650f8\" class=\"direction-step\"><strong>Pr\u00e9pare la base de glace<\/strong><br \/>Verse les pommes refroidies dans le pot de ton Ninja Creami (ou de la Swirl). Ajoute les yaourts grecs et le lait concentr\u00e9. M\u00e9lange grossi\u00e8rement : il doit rester des morceaux de pommes visibles pour plus de gourmandise.<\/li><li id=\"wpzoom-rcb-direction-step-68c9bb68650f9\" class=\"direction-step\"><strong>Cong\u00e8le la pr\u00e9paration<\/strong><br \/>Place le pot bien \u00e0 plat au cong\u00e9lateur et laisse-le reposer pendant\u00a0<strong>24 heures<\/strong>.<\/li><li id=\"wpzoom-rcb-direction-step-1758051410118250\" class=\"direction-step\"><strong>Passe en glace<\/strong><br \/>Le lendemain, ins\u00e8re le pot dans ta machine et lance le programme\u00a0<strong>Ice Cream<\/strong>.<\/li><li id=\"wpzoom-rcb-direction-step-1758051472018275\" class=\"direction-step\"><strong>Ajuste la texture<\/strong><br \/>Si la glace est un peu trop ferme, ajoute une cuill\u00e8re \u00e0 soupe de lait froid sur le dessus et relance un cycle\u00a0<strong>Re-spin<\/strong>\u00a0pour obtenir une texture plus cr\u00e9meuse.<\/li><li id=\"wpzoom-rcb-direction-step-1758051473117280\" class=\"direction-step\"><strong>Finition glace italienne<\/strong><br \/>Pour un r\u00e9sultat encore plus a\u00e9rien et gourmand, passe la glace dans l\u2019accessoire glace italienne du Ninja Swirl : tu obtiendras une texture onctueuse et fondante, comme au glacier.<\/li><\/ul><\/div><div class=\"recipe-card-notes\">\n\t\t\t\t\t<h3 class=\"notes-title\">Notes<\/h3>\n\t\t\t\t\t<ul class=\"recipe-card-notes-list\"><li>Tu peux varier cette recette en ajoutant quelques noix caram\u00e9lis\u00e9es ou des noisettes grill\u00e9es pour apporter du croquant. <\/li><li>Le sirop d\u2019\u00e9rable peut \u00eatre remplac\u00e9 par du miel ou du sirop d\u2019agave si tu pr\u00e9f\u00e8res une autre note sucr\u00e9e. <\/li><li>Pour adoucir l\u2019intensit\u00e9 de la cannelle, tu peux y ajouter une pointe de vanille liquide ou en poudre. <\/li><li>Enfin, n\u2019h\u00e9site pas \u00e0 garder quelques morceaux de pommes caram\u00e9lis\u00e9es de c\u00f4t\u00e9 pour les ajouter en topping au moment de servir : un vrai r\u00e9gal aux saveurs automnales.<\/li><\/ul>\n\t\t\t\t<\/div><script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"name\":\"Glace aux pommes r\u00f4ties et au sirop d'\u00e9rable\",\"image\":[\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png\",\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36-500x500.png\",\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36-500x375.png\",\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36-480x270.png\"],\"description\":\"\",\"keywords\":\"\",\"author\":{\"@type\":\"Person\",\"name\":\"Julien\"},\"datePublished\":\"2025-09-16T19:43:10+00:00\",\"prepTime\":\"\",\"cookTime\":\"\",\"totalTime\":\"\",\"recipeCategory\":[\"Glaces\"],\"recipeCuisine\":[],\"recipeYield\":[\"4\",\"4 portions\"],\"nutrition\":{\"@type\":\"NutritionInformation\"},\"recipeIngredient\":[\"3 pommes\",\"2 pots de yaourt grec\",\"1 morceau de beurre\",\"3 cuill\u00e8res \u00e0 soupe de sirop d\u2019\u00e9rable\",\"Environ 3 cuill\u00e8res \u00e0 soupe de cassonade\",\"Cannelle\",\"10 \u00e0 20 g de lait concentr\u00e9 sucr\u00e9\"],\"recipeInstructions\":[{\"@type\":\"HowToStep\",\"name\":\"Pr\u00e9pare les pommes r\u00f4ties\u00c9pluche les pommes, retire le c\u0153ur puis coupe-les en petits morceaux. Mets-les dans une casserole avec le beurre, le sirop d\u2019\u00e9rable, la cassonade et une bonne dose de cannelle. Fais cuire \u00e0 feu moyen jusqu\u2019\u00e0 ce que les pommes soient bien tendres, caram\u00e9lis\u00e9es et dor\u00e9es. Si n\u00e9cessaire, ajoute un petit filet d\u2019eau pour \u00e9viter que \u00e7a accroche.\",\"text\":\"Pr\u00e9pare les pommes r\u00f4ties\u00c9pluche les pommes, retire le c\u0153ur puis coupe-les en petits morceaux. Mets-les dans une casserole avec le beurre, le sirop d\u2019\u00e9rable, la cassonade et une bonne dose de cannelle. Fais cuire \u00e0 feu moyen jusqu\u2019\u00e0 ce que les pommes soient bien tendres, caram\u00e9lis\u00e9es et dor\u00e9es. Si n\u00e9cessaire, ajoute un petit filet d\u2019eau pour \u00e9viter que \u00e7a accroche.\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/sorvete-de-maca-assada-e-xarope-de-bordo\\\/#wpzoom-rcb-direction-step-68c9bb68650f6\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Laisse refroidirQuand les pommes ont une belle couleur caramel et une texture fondante, retire la casserole du feu et laisse compl\u00e8tement refroidir.\",\"text\":\"Laisse refroidirQuand les pommes ont une belle couleur caramel et une texture fondante, retire la casserole du feu et laisse compl\u00e8tement refroidir.\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/sorvete-de-maca-assada-e-xarope-de-bordo\\\/#wpzoom-rcb-direction-step-68c9bb68650f7\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Pr\u00e9pare la base de glaceVerse les pommes refroidies dans le pot de ton Ninja Creami (ou de la Swirl). Ajoute les yaourts grecs et le lait concentr\u00e9. M\u00e9lange grossi\u00e8rement : il doit rester des morceaux de pommes visibles pour plus de gourmandise.\",\"text\":\"Pr\u00e9pare la base de glaceVerse les pommes refroidies dans le pot de ton Ninja Creami (ou de la Swirl). Ajoute les yaourts grecs et le lait concentr\u00e9. M\u00e9lange grossi\u00e8rement : il doit rester des morceaux de pommes visibles pour plus de gourmandise.\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/sorvete-de-maca-assada-e-xarope-de-bordo\\\/#wpzoom-rcb-direction-step-68c9bb68650f8\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Cong\u00e8le la pr\u00e9parationPlace le pot bien \u00e0 plat au cong\u00e9lateur et laisse-le reposer pendant\u00a024 heures.\",\"text\":\"Cong\u00e8le la pr\u00e9parationPlace le pot bien \u00e0 plat au cong\u00e9lateur et laisse-le reposer pendant\u00a024 heures.\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/sorvete-de-maca-assada-e-xarope-de-bordo\\\/#wpzoom-rcb-direction-step-68c9bb68650f9\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Passe en glaceLe lendemain, ins\u00e8re le pot dans ta machine et lance le programme\u00a0Ice Cream.\",\"text\":\"Passe en glaceLe lendemain, ins\u00e8re le pot dans ta machine et lance le programme\u00a0Ice Cream.\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/sorvete-de-maca-assada-e-xarope-de-bordo\\\/#wpzoom-rcb-direction-step-1758051410118250\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Ajuste la textureSi la glace est un peu trop ferme, ajoute une cuill\u00e8re \u00e0 soupe de lait froid sur le dessus et relance un cycle\u00a0Re-spin\u00a0pour obtenir une texture plus cr\u00e9meuse.\",\"text\":\"Ajuste la textureSi la glace est un peu trop ferme, ajoute une cuill\u00e8re \u00e0 soupe de lait froid sur le dessus et relance un cycle\u00a0Re-spin\u00a0pour obtenir une texture plus cr\u00e9meuse.\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/sorvete-de-maca-assada-e-xarope-de-bordo\\\/#wpzoom-rcb-direction-step-1758051472018275\",\"image\":\"\"},{\"@type\":\"HowToStep\",\"name\":\"Finition glace italiennePour un r\u00e9sultat encore plus a\u00e9rien et gourmand, passe la glace dans l\u2019accessoire glace italienne du Ninja Swirl : tu obtiendras une texture onctueuse et fondante, comme au glacier.\",\"text\":\"Finition glace italiennePour un r\u00e9sultat encore plus a\u00e9rien et gourmand, passe la glace dans l\u2019accessoire glace italienne du Ninja Swirl : tu obtiendras une texture onctueuse et fondante, comme au glacier.\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/sorvete-de-maca-assada-e-xarope-de-bordo\\\/#wpzoom-rcb-direction-step-1758051473117280\",\"image\":\"\"}]}<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea quer um sorvete com cheiro de outono e sobremesas caseiras? Esta receita vai te encantar. Imagine\u2026<\/p>","protected":false},"author":1,"featured_media":1039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glaces"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glace aux pommes r\u00f4ties et au sirop d&#039;\u00e9rable pour Ninja Creami &amp; Swirl - Ninja Ice Cream<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ninja-icecream.com\/pt\/sorvete-de-maca-assada-e-xarope-de-bordo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glace aux pommes r\u00f4ties et au sirop d&#039;\u00e9rable pour Ninja Creami &amp; Swirl - Ninja Ice Cream\" \/>\n<meta property=\"og:description\" content=\"Tu veux une glace qui sent bon l\u2019automne et les desserts faits maison ? Cette recette va te faire fondre. Imagine des\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ninja-icecream.com\/pt\/sorvete-de-maca-assada-e-xarope-de-bordo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ninja Ice Cream\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T19:43:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T14:58:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/\"},\"author\":{\"name\":\"Julien\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/#\\\/schema\\\/person\\\/388034eb867ef31a9300cb63869bc110\"},\"headline\":\"Glace aux pommes r\u00f4ties et au sirop d&rsquo;\u00e9rable pour Ninja Creami &#038; Swirl\",\"datePublished\":\"2025-09-16T19:43:10+00:00\",\"dateModified\":\"2026-02-11T14:58:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/\"},\"wordCount\":120,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png\",\"articleSection\":[\"Glaces\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/\",\"name\":\"Glace aux pommes r\u00f4ties et au sirop d'\u00e9rable pour Ninja Creami & Swirl - Ninja Ice Cream\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png\",\"datePublished\":\"2025-09-16T19:43:10+00:00\",\"dateModified\":\"2026-02-11T14:58:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/#\\\/schema\\\/person\\\/388034eb867ef31a9300cb63869bc110\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png\",\"contentUrl\":\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/glace-aux-pommes-roties-et-au-sirop-derable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ninja-icecream.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glace aux pommes r\u00f4ties et au sirop d&rsquo;\u00e9rable pour Ninja Creami &#038; Swirl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/#website\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/\",\"name\":\"Ninja Ice Cream\",\"description\":\"Le site 100% d\u00e9di\u00e9 aux glaces maison avec Ninja.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ninja-icecream.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/#\\\/schema\\\/person\\\/388034eb867ef31a9300cb63869bc110\",\"name\":\"Julien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-ChatGPT-Image-17-sept.-2025-13_32_02-96x96.png\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-ChatGPT-Image-17-sept.-2025-13_32_02-96x96.png\",\"contentUrl\":\"https:\\\/\\\/ninja-icecream.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-ChatGPT-Image-17-sept.-2025-13_32_02-96x96.png\",\"caption\":\"Julien\"},\"description\":\"Passionn\u00e9 de desserts glac\u00e9s et de cuisine cr\u00e9ative, Julien a cr\u00e9\u00e9 Ninja-Icecream pour partager ses recettes, astuces et exp\u00e9riences gourmandes. Toujours en qu\u00eate de nouvelles saveurs, il aime transformer des ingr\u00e9dients simples en glaces surprenantes et raffin\u00e9es. Curieux et inventif, Julien teste sans cesse de nouvelles associations : fruits de saison, \u00e9pices venues d\u2019ailleurs, ou encore touches chocolat\u00e9es r\u00e9confortantes. Son objectif ? Rendre la glace accessible \u00e0 tous, qu\u2019on soit d\u00e9butant ou fin gourmet, et montrer qu\u2019avec un peu d\u2019audace, on peut cr\u00e9er des desserts dignes des meilleures glaciers\u2026 directement chez soi. Quand il n\u2019est pas derri\u00e8re son Ninja Creami, Julien aime voyager pour d\u00e9couvrir des traditions culinaires, ou encore passer du temps en cuisine avec ses proches, toujours autour d\u2019un bon dessert glac\u00e9.\",\"sameAs\":[\"https:\\\/\\\/ninja-icecream.com\"],\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/pt\\\/author\\\/ninja-ice-cream\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorvete de ma\u00e7\u00e3 assada e xarope de bordo para Ninja Creami &amp; Swirl - Ninja Ice Cream","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ninja-icecream.com\/pt\/sorvete-de-maca-assada-e-xarope-de-bordo\/","og_locale":"pt_PT","og_type":"article","og_title":"Glace aux pommes r\u00f4ties et au sirop d'\u00e9rable pour Ninja Creami & Swirl - Ninja Ice Cream","og_description":"Tu veux une glace qui sent bon l\u2019automne et les desserts faits maison ? Cette recette va te faire fondre. Imagine des\u2026","og_url":"https:\/\/ninja-icecream.com\/pt\/sorvete-de-maca-assada-e-xarope-de-bordo\/","og_site_name":"Ninja Ice Cream","article_published_time":"2025-09-16T19:43:10+00:00","article_modified_time":"2026-02-11T14:58:43+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png","type":"image\/png"}],"author":"Julien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julien","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#article","isPartOf":{"@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/"},"author":{"name":"Julien","@id":"https:\/\/ninja-icecream.com\/#\/schema\/person\/388034eb867ef31a9300cb63869bc110"},"headline":"Glace aux pommes r\u00f4ties et au sirop d&rsquo;\u00e9rable pour Ninja Creami &#038; Swirl","datePublished":"2025-09-16T19:43:10+00:00","dateModified":"2026-02-11T14:58:43+00:00","mainEntityOfPage":{"@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/"},"wordCount":120,"commentCount":0,"image":{"@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#primaryimage"},"thumbnailUrl":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png","articleSection":["Glaces"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/","url":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/","name":"Sorvete de ma\u00e7\u00e3 assada e xarope de bordo para Ninja Creami &amp; Swirl - Ninja Ice Cream","isPartOf":{"@id":"https:\/\/ninja-icecream.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#primaryimage"},"image":{"@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#primaryimage"},"thumbnailUrl":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png","datePublished":"2025-09-16T19:43:10+00:00","dateModified":"2026-02-11T14:58:43+00:00","author":{"@id":"https:\/\/ninja-icecream.com\/#\/schema\/person\/388034eb867ef31a9300cb63869bc110"},"breadcrumb":{"@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#primaryimage","url":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png","contentUrl":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-16-sept.-2025-a-21_42_36.png","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/ninja-icecream.com\/glace-aux-pommes-roties-et-au-sirop-derable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ninja-icecream.com\/"},{"@type":"ListItem","position":2,"name":"Glace aux pommes r\u00f4ties et au sirop d&rsquo;\u00e9rable pour Ninja Creami &#038; Swirl"}]},{"@type":"WebSite","@id":"https:\/\/ninja-icecream.com\/#website","url":"https:\/\/ninja-icecream.com\/","name":"Sorvete Ninja","description":"O site 100% \u00e9 dedicado ao sorvete caseiro feito com a m\u00e1quina Ninja.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ninja-icecream.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/ninja-icecream.com\/#\/schema\/person\/388034eb867ef31a9300cb63869bc110","name":"Julian","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/cropped-ChatGPT-Image-17-sept.-2025-13_32_02-96x96.png","url":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/cropped-ChatGPT-Image-17-sept.-2025-13_32_02-96x96.png","contentUrl":"https:\/\/ninja-icecream.com\/wp-content\/uploads\/2025\/09\/cropped-ChatGPT-Image-17-sept.-2025-13_32_02-96x96.png","caption":"Julien"},"description":"Apaixonado por sobremesas geladas e culin\u00e1ria criativa, Julien criou a Ninja-Icecream para compartilhar suas receitas, dicas e experi\u00eancias gastron\u00f4micas. Sempre em busca de novos sabores, ele adora transformar ingredientes simples em sorvetes surpreendentes e sofisticados. Curioso e inventivo, Julien experimenta constantemente novas combina\u00e7\u00f5es: frutas da esta\u00e7\u00e3o, especiarias ex\u00f3ticas ou toques reconfortantes de chocolate. Seu objetivo? Tornar o sorvete acess\u00edvel a todos, de iniciantes a gourmets experientes, e mostrar que, com um pouco de ousadia, \u00e9 poss\u00edvel criar sobremesas dignas das melhores sorveterias... no conforto da sua casa. Quando n\u00e3o est\u00e1 por tr\u00e1s da Ninja-Icecream, Julien gosta de viajar para descobrir tradi\u00e7\u00f5es culin\u00e1rias ou passar tempo na cozinha com seus entes queridos, sempre apreciando uma deliciosa sobremesa gelada.","sameAs":["https:\/\/ninja-icecream.com"],"url":"https:\/\/ninja-icecream.com\/pt\/author\/ninja-ice-cream\/"}]}},"_links":{"self":[{"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/posts\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/comments?post=1038"}],"version-history":[{"count":4,"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/posts\/1038\/revisions"}],"predecessor-version":[{"id":1802,"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/posts\/1038\/revisions\/1802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/media\/1039"}],"wp:attachment":[{"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/media?parent=1038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/categories?post=1038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ninja-icecream.com\/pt\/wp-json\/wp\/v2\/tags?post=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}