{"id":18,"count":16,"description":"Envie de fra\u00eecheur et de l\u00e9g\u00e8ret\u00e9 ? Les sorbets maison sont parfaits pour sublimer les fruits tout en profitant d\u2019une texture glac\u00e9e irr\u00e9sistible. Avec ta machine Ninja - qu\u2019il s\u2019agisse du Creami, du Swirl ou du Slushi - transforme en quelques minutes tes fruits pr\u00e9f\u00e9r\u00e9s en desserts glac\u00e9s sains et savoureux.\r\n\r\nMangue, fraise, framboise, citron ou fruits exotiques : nos recettes de sorbets sont simples, naturelles et personnalisables selon tes envies. Sans produits laitiers et souvent sans sucre ajout\u00e9, elles sont id\u00e9ales pour les amateurs de fra\u00eecheur fruit\u00e9e.","link":"https:\/\/ninja-icecream.com\/en\/category\/sorbets\/","name":"Sorbets","slug":"sorbets","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recettes Sorbets Ninja Creami &amp; Swirl : 25+ Id\u00e9es Fruit\u00e9es<\/title>\n<meta name=\"description\" content=\"25+ recettes sorbets Ninja Creami &amp; Swirl : fraise, framboise, citron, melon. Sorbets fruit\u00e9s, sans sucre et vegan. Parfaits pour l&#039;\u00e9t\u00e9 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ninja-icecream.com\/en\/category\/sorbets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recettes Sorbets Ninja Creami &amp; Swirl : 25+ Id\u00e9es Fruit\u00e9es\" \/>\n<meta property=\"og:description\" content=\"25+ recettes sorbets Ninja Creami &amp; Swirl : fraise, framboise, citron, melon. Sorbets fruit\u00e9s, sans sucre et vegan. Parfaits pour l&#039;\u00e9t\u00e9 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ninja-icecream.com\/en\/category\/sorbets\/\" \/>\n<meta property=\"og:site_name\" content=\"Ninja Ice Cream\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/category\\\/sorbets\\\/\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/category\\\/sorbets\\\/\",\"name\":\"Recettes Sorbets Ninja Creami & Swirl : 25+ Id\u00e9es Fruit\u00e9es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/#website\"},\"description\":\"25+ recettes sorbets Ninja Creami & Swirl : fraise, framboise, citron, melon. Sorbets fruit\u00e9s, sans sucre et vegan. Parfaits pour l'\u00e9t\u00e9 !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/category\\\/sorbets\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/category\\\/sorbets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ninja-icecream.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sorbets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ninja-icecream.com\\\/#website\",\"url\":\"https:\\\/\\\/ninja-icecream.com\\\/\",\"name\":\"Ninja Ice Cream\",\"description\":\"Le site 100% d\u00e9di\u00e9 aux glaces maison avec Ninja.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ninja-icecream.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recettes Sorbets Ninja Creami & Swirl : 25+ Id\u00e9es Fruit\u00e9es","description":"25+ Ninja Creami &amp; Swirl sorbet recipes: strawberry, raspberry, lemon, melon. Fruity, sugar-free, vegan sorbets. Perfect for summer!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ninja-icecream.com\/en\/category\/sorbets\/","og_locale":"en_US","og_type":"article","og_title":"Recettes Sorbets Ninja Creami & Swirl : 25+ Id\u00e9es Fruit\u00e9es","og_description":"25+ recettes sorbets Ninja Creami & Swirl : fraise, framboise, citron, melon. Sorbets fruit\u00e9s, sans sucre et vegan. Parfaits pour l'\u00e9t\u00e9 !","og_url":"https:\/\/ninja-icecream.com\/en\/category\/sorbets\/","og_site_name":"Ninja Ice Cream","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ninja-icecream.com\/category\/sorbets\/","url":"https:\/\/ninja-icecream.com\/category\/sorbets\/","name":"Ninja Creami &amp; Swirl Sorbet Recipes: 25+ Fruity Ideas","isPartOf":{"@id":"https:\/\/ninja-icecream.com\/#website"},"description":"25+ Ninja Creami &amp; Swirl sorbet recipes: strawberry, raspberry, lemon, melon. Fruity, sugar-free, vegan sorbets. Perfect for summer!","breadcrumb":{"@id":"https:\/\/ninja-icecream.com\/category\/sorbets\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ninja-icecream.com\/category\/sorbets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ninja-icecream.com\/"},{"@type":"ListItem","position":2,"name":"Sorbets"}]},{"@type":"WebSite","@id":"https:\/\/ninja-icecream.com\/#website","url":"https:\/\/ninja-icecream.com\/","name":"Ninja Ice Cream","description":"The 100% website dedicated to homemade ice cream with Ninja.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ninja-icecream.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ninja-icecream.com\/en\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ninja-icecream.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ninja-icecream.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ninja-icecream.com\/en\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}